{"id":22134,"date":"2026-01-10T06:02:00","date_gmt":"2026-01-10T05:02:00","guid":{"rendered":"https:\/\/www.sohorse.eu\/?p=22134"},"modified":"2026-03-03T17:37:40","modified_gmt":"2026-03-03T16:37:40","slug":"abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi","status":"publish","type":"post","link":"https:\/\/www.sohorse.eu\/en\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/","title":{"rendered":"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Ce vendredi soir \u00e0 Abu Dhabi,&nbsp;<strong>Abdel Sa\u00efd<\/strong> a frapp\u00e9 juste dans la 1,50 m du CSI 5*, coupant la politesse \u00e0 \u00ab\u00a0Jo\u00a0\u00bb Stockdale pour un fifrelin et rappelant qu\u2019en terrain rapide, il reste un client tr\u00e8s s\u00e9rieux.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un CSI 5* lanc\u00e9 \u00e0 pleine vitesse<\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>L\u2019\u00e9preuve cot\u00e9e \u00e0 1,50 m du&nbsp;CSI 5* Abu Dhabi&nbsp;avait tout du pi\u00e8ge classique : trac\u00e9 fluide, oxers ouverts, chronom\u00e8tre serr\u00e9. Quarante-et-un duos au d\u00e9part, une pression des \u00e9preuves qui comptent.<\/p>\n\n\n\n<p>Dans ce contexte, Abdel Sa\u00efd a d\u00e9roul\u00e9 avec Arp\u00e8ge du Ru Sans un souffle de trop, sans un geste superflu. R\u00e9sultat : un parcours vierge et un temps de&nbsp;54\u2019\u201946, r\u00e9f\u00e9rence que personne ne parviendra \u00e0 faire tomber.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stockdale \u00e0 un souffle, Pettersson H\u00e4ggstr\u00f6m en embuscade<\/h3>\n\n\n\n<p>La Su\u00e9doise&nbsp;<strong>Antonia Pettersson H\u00e4ggstr\u00f6m<\/strong>&nbsp;avait pourtant fait trembler le leader. En selle sur&nbsp;<strong>Komme Vous<\/strong>, elle arr\u00eatait la montre en&nbsp;56\u2019\u201947, s\u2019installant provisoirement au deuxi\u00e8me rang.<\/p>\n\n\n\n<p>Mais Stockdale, avant-dernier \u00e0 s\u2019\u00e9lancer avec&nbsp;<strong>Laska JDV<\/strong>, est pass\u00e9 tout pr\u00e8s du hold-up. Tr\u00e8s pr\u00e8s. Trop pr\u00e8s.&nbsp;+1\u2019\u201907, et une deuxi\u00e8me place frustrante, mais solide.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Arp\u00e8ge du Ru, une valeur s\u00fbre qui empile les victoires<\/h3>\n\n\n\n<p><strong>Arp\u00e8ge du Ru<\/strong>&nbsp;(Apache d&rsquo;Adriers \/ Quat&rsquo;sous) et Said c&rsquo;est d\u00e9sormais une vieille paire qui connait la musique. La Jument Selle Fran\u00e7ais a 16 ans. 7ans que le couple \u00e9volue ensemble et continue d\u2019empiler les lignes \u00e0 son palmar\u00e8s. Avec cette victoire \u00e0 Abou Dabi, elle atteint d\u00e9sormais&nbsp;25 <\/p>\n\n\n\n<p>succ\u00e8s internationaux. Rare \u00e0 ce niveau.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"945\" height=\"631\" data-src=\"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/2025.02.15.99.99-Doha-CSI-3-WC-GP-Abdel-Said-Arpege-du-Ru-2.jpg.webp\" alt=\"Abdel Said\" class=\"wp-image-22139 lazyload\" data-srcset=\"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/2025.02.15.99.99-Doha-CSI-3-WC-GP-Abdel-Said-Arpege-du-Ru-2.jpg.webp 945w, https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/2025.02.15.99.99-Doha-CSI-3-WC-GP-Abdel-Said-Arpege-du-Ru-2.jpg-768x513.webp 768w\" data-sizes=\"(max-width: 945px) 100vw, 945px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 945px; --smush-placeholder-aspect-ratio: 945\/631;\" \/><figcaption class=\"wp-element-caption\">(\u00a9Al Shaqab)<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Il y a un peu moins d&rsquo;un an, le duo s&rsquo;imposait dans la Coupe du monde \u00e0 Doha. Avec Abdel Sa\u00efd, l\u2019alchimie est \u00e9vidente : le couple se connait par coeur et \u00e7a se voit. Vitesse ma\u00eetris\u00e9e, trajectoires nettes, et une lecture parfaite du trac\u00e9. Le genre de duo qui transforme une \u00e9preuve rapide en d\u00e9monstration.<\/p>\n\n\n\n<p>Mais le week-end est loin d&rsquo;\u00eatre termin\u00e9 pour Abdel. Il vole (comme l&rsquo;ann\u00e9e pass\u00e9e voir notre article <a href=\"https:\/\/www.sohorse.eu\/en\/reportages\/2025\/01\/13\/le-week-end-un-peu-fou-dabdel-said\/\">here<\/a>), en effet, entre les 5* d&rsquo;Abu Dhabi et Doha. Une course qui \u00e0 ce stade ne semble pas freiner les performances du cavalier belge.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beaucoup de sans-faute, peu d\u2019\u00e9lus<\/h3>\n\n\n\n<p>\u00c0 Abu Dhabi, ils \u00e9taient&nbsp;17 duos sans p\u00e9nalit\u00e9, mais seulement&nbsp;13 class\u00e9s. La s\u00e9lection s\u2019est faite \u00e0 la montre, sans piti\u00e9.<br>Les Allemands&nbsp;Daniel Deusser&nbsp;(4e avec&nbsp;<strong>Gangster van het Noddevelt<\/strong>) and&nbsp;<strong>Sophie Hinners<\/strong>&nbsp;(5e avec&nbsp;<strong>Iron Dames Kaleni Jo<\/strong>) confirment leur statut.<\/p>\n\n\n\n<p>\u00c0 noter aussi la belle&nbsp;12e place&nbsp;de l\u2019\u00c9mirati&nbsp;<strong>Omar Abdul Aziz Al Marzooqi<\/strong>&nbsp;with&nbsp;<strong>Enjoy de la M\u00fbre<\/strong> toujours consistant, sous les yeux de son public conquis.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2280\" height=\"1520\" data-src=\"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-2280x1520.jpg\" alt=\"\" class=\"wp-image-22135 lazyload\" data-srcset=\"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-2280x1520.jpg 2280w, https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-1140x760.jpg 1140w, https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-768x512.jpg 768w, https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-1536x1024.jpg 1536w, https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-2048x1365.jpg 2048w, https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/104A7296-1320x880.jpg 1320w\" data-sizes=\"(max-width: 2280px) 100vw, 2280px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2280px; --smush-placeholder-aspect-ratio: 2280\/1520;\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Find <a href=\"https:\/\/www.longinestiming.com\/equestrian\/2026\/uae-presidents-cup-abu-dhabi\/resultlist_10.html\">les r\u00e9sultats complets de l&rsquo;\u00e9preuve 1m50 d&rsquo;Abu Dhabi ici<\/a><\/p>\n\n\n\n<p>(Photo cover \u00a9 Al Shaqab)<\/p>","protected":false},"excerpt":{"rendered":"<p>Ce vendredi soir \u00e0 Abu Dhabi,&nbsp;Abdel Sa\u00efd a frapp\u00e9 juste dans la 1,50 m du CSI 5*, coupant la politesse \u00e0 \u00ab\u00a0Jo\u00a0\u00bb Stockdale pour un fifrelin et rappelant qu\u2019en terrain rapide, il reste un client tr\u00e8s s\u00e9rieux. Un CSI 5* lanc\u00e9 \u00e0 pleine vitesse L\u2019\u00e9preuve cot\u00e9e \u00e0 1,50 m du&nbsp;CSI 5* Abu Dhabi&nbsp;avait tout du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-22134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi &#8212; So Horse<\/title>\n<meta name=\"description\" content=\"Abdel Sa\u00efd s\u2019impose dans la 1,50 m du CSI 5* d\u2019Abou Dabi avec Arp\u00e8ge du Ru, devan\u00e7ant Joseph Stockdale pour un souffle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sohorse.eu\/en\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi &#8212; So Horse\" \/>\n<meta property=\"og:description\" content=\"Abdel Sa\u00efd s\u2019impose dans la 1,50 m du CSI 5* d\u2019Abou Dabi avec Arp\u00e8ge du Ru, devan\u00e7ant Joseph Stockdale pour un souffle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sohorse.eu\/en\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/\" \/>\n<meta property=\"og:site_name\" content=\"So Horse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sohorse.official\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-10T05:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T16:37:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/cover-So-Horse-13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Boulanger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Boulanger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Boulanger\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#\\\/schema\\\/person\\\/8ec889a1dca0caa9c3fc409225ae3ca4\"},\"headline\":\"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi\",\"datePublished\":\"2026-01-10T05:02:00+00:00\",\"dateModified\":\"2026-03-03T16:37:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/\"},\"wordCount\":507,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sohorse.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cover-So-Horse-13.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/\",\"url\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/\",\"name\":\"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi &#8212; So Horse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sohorse.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cover-So-Horse-13.jpg\",\"datePublished\":\"2026-01-10T05:02:00+00:00\",\"dateModified\":\"2026-03-03T16:37:40+00:00\",\"description\":\"Abdel Sa\u00efd s\u2019impose dans la 1,50 m du CSI 5* d\u2019Abou Dabi avec Arp\u00e8ge du Ru, devan\u00e7ant Joseph Stockdale pour un souffle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sohorse.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cover-So-Horse-13.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sohorse.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cover-So-Horse-13.jpg\",\"width\":1000,\"height\":573,\"caption\":\"Abdel Said\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/news\\\/2026\\\/01\\\/10\\\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"So Horse\",\"item\":\"https:\\\/\\\/www.sohorse.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.sohorse.eu\\\/categorie\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.sohorse.eu\\\/\",\"name\":\"So Horse\",\"description\":\"L\u2019actu sur les chevaux autrement. Les sports \u00e9questres, l\u2019\u00e9levage et les ventes aux ench\u00e8res\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sohorse.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#organization\",\"name\":\"So Horse\",\"url\":\"https:\\\/\\\/www.sohorse.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sohorse.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logog.png\",\"contentUrl\":\"https:\\\/\\\/www.sohorse.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logog.png\",\"width\":296,\"height\":146,\"caption\":\"So Horse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sohorse.official\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sohorse.eu\\\/#\\\/schema\\\/person\\\/8ec889a1dca0caa9c3fc409225ae3ca4\",\"name\":\"S\u00e9bastien Boulanger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/958b7300960313a7bf10ee053221a7a94b9056219a3a03458f5a0db80e1e25e3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/958b7300960313a7bf10ee053221a7a94b9056219a3a03458f5a0db80e1e25e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/958b7300960313a7bf10ee053221a7a94b9056219a3a03458f5a0db80e1e25e3?s=96&d=mm&r=g\",\"caption\":\"S\u00e9bastien Boulanger\"},\"url\":\"https:\\\/\\\/www.sohorse.eu\\\/en\\\/author\\\/seb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi &#8212; So Horse","description":"Abdel Sa\u00efd s\u2019impose dans la 1,50 m du CSI 5* d\u2019Abou Dabi avec Arp\u00e8ge du Ru, devan\u00e7ant Joseph Stockdale pour un souffle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sohorse.eu\/en\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/","og_locale":"en_GB","og_type":"article","og_title":"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi &#8212; So Horse","og_description":"Abdel Sa\u00efd s\u2019impose dans la 1,50 m du CSI 5* d\u2019Abou Dabi avec Arp\u00e8ge du Ru, devan\u00e7ant Joseph Stockdale pour un souffle.","og_url":"https:\/\/www.sohorse.eu\/en\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/","og_site_name":"So Horse","article_publisher":"https:\/\/www.facebook.com\/sohorse.official","article_published_time":"2026-01-10T05:02:00+00:00","article_modified_time":"2026-03-03T16:37:40+00:00","og_image":[{"width":1000,"height":573,"url":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/cover-So-Horse-13.jpg","type":"image\/jpeg"}],"author":"S\u00e9bastien Boulanger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"S\u00e9bastien Boulanger","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#article","isPartOf":{"@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/"},"author":{"name":"S\u00e9bastien Boulanger","@id":"https:\/\/www.sohorse.eu\/#\/schema\/person\/8ec889a1dca0caa9c3fc409225ae3ca4"},"headline":"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi","datePublished":"2026-01-10T05:02:00+00:00","dateModified":"2026-03-03T16:37:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/"},"wordCount":507,"publisher":{"@id":"https:\/\/www.sohorse.eu\/#organization"},"image":{"@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/cover-So-Horse-13.jpg","articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/","url":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/","name":"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi &#8212; So Horse","isPartOf":{"@id":"https:\/\/www.sohorse.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#primaryimage"},"image":{"@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/cover-So-Horse-13.jpg","datePublished":"2026-01-10T05:02:00+00:00","dateModified":"2026-03-03T16:37:40+00:00","description":"Abdel Sa\u00efd s\u2019impose dans la 1,50 m du CSI 5* d\u2019Abou Dabi avec Arp\u00e8ge du Ru, devan\u00e7ant Joseph Stockdale pour un souffle.","breadcrumb":{"@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#primaryimage","url":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/cover-So-Horse-13.jpg","contentUrl":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2026\/01\/cover-So-Horse-13.jpg","width":1000,"height":573,"caption":"Abdel Said"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sohorse.eu\/news\/2026\/01\/10\/abdel-said-arpege-du-ru-victoire-csi5-abu-dhabi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"So Horse","item":"https:\/\/www.sohorse.eu\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.sohorse.eu\/categorie\/news\/"},{"@type":"ListItem","position":3,"name":"Abdel Sa\u00efd sort le chrono parfait : Arp\u00e8ge du Ru plus rapide que tout le monde \u00e0 Abu Dhabi"}]},{"@type":"WebSite","@id":"https:\/\/www.sohorse.eu\/#website","url":"https:\/\/www.sohorse.eu\/","name":"So Horse","description":"L\u2019actu sur les chevaux autrement. Les sports \u00e9questres, l\u2019\u00e9levage et les ventes aux ench\u00e8res","publisher":{"@id":"https:\/\/www.sohorse.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sohorse.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.sohorse.eu\/#organization","name":"So Horse","url":"https:\/\/www.sohorse.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.sohorse.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2024\/03\/logog.png","contentUrl":"https:\/\/www.sohorse.eu\/wp-content\/uploads\/2024\/03\/logog.png","width":296,"height":146,"caption":"So Horse"},"image":{"@id":"https:\/\/www.sohorse.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sohorse.official"]},{"@type":"Person","@id":"https:\/\/www.sohorse.eu\/#\/schema\/person\/8ec889a1dca0caa9c3fc409225ae3ca4","name":"S\u00e9bastien Boulanger","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/958b7300960313a7bf10ee053221a7a94b9056219a3a03458f5a0db80e1e25e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/958b7300960313a7bf10ee053221a7a94b9056219a3a03458f5a0db80e1e25e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/958b7300960313a7bf10ee053221a7a94b9056219a3a03458f5a0db80e1e25e3?s=96&d=mm&r=g","caption":"S\u00e9bastien Boulanger"},"url":"https:\/\/www.sohorse.eu\/en\/author\/seb\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/posts\/22134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/comments?post=22134"}],"version-history":[{"count":3,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/posts\/22134\/revisions"}],"predecessor-version":[{"id":29036,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/posts\/22134\/revisions\/29036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/media\/22140"}],"wp:attachment":[{"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/media?parent=22134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/categories?post=22134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sohorse.eu\/en\/wp-json\/wp\/v2\/tags?post=22134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}